{"id":14885,"date":"2022-10-14T09:06:37","date_gmt":"2022-10-14T08:06:37","guid":{"rendered":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/"},"modified":"2025-08-27T08:47:54","modified_gmt":"2025-08-27T07:47:54","slug":"directores-seglares-2","status":"publish","type":"post","link":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/","title":{"rendered":"Encuentro de directores de Obras gestionadas por seglares"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.18.0&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<\/p>\n<div class=\"et_pb_column et_pb_column_4_4 et_pb_column_0  et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_0  et_pb_text_align_justified et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<p>Durante los d\u00edas 13 y 14 de octubre, en la casa salesiana de Sanl\u00facar la Mayor, se llev\u00f3 a cabo un nuevo encuentro de directores de obras gestionadas por seglares de la Inspector\u00eda Salesiana Mar\u00eda Auxiliadora.<\/p>\n<p>El sentido de las jornadas de trabajo, que cont\u00f3 con la coordinaci\u00f3n de Fernando B\u00e1\u00f1ez como consejero responsable de la animaci\u00f3n y el acompa\u00f1amiento de las presencias, y estuvo centrado en la comunicaci\u00f3n salesiana de la mano de la Delegaci\u00f3n. Carlos Mart\u00edn, delegado inspectorial, junto a Antonino G\u00f3mez y Jos\u00e9 Luis Garc\u00eda, profesionales del equipo encargados de la gesti\u00f3n web, la creaci\u00f3n de contenidos en redes, el acompa\u00f1amiento de peticiones de imagen corporativa o las propuestas de actividades estrat\u00e9gicas, pudieron profundizar en diferentes facetas del Plan Inspectorial de Comunicaci\u00f3n y la relaci\u00f3n del mismo con el documento inspectorial \u2018Obras gestionadas por seglares en la Inspector\u00eda Mar\u00eda Auxiliadora\u2019, adem\u00e1s del Cuadro de Referencia de la Pastoral Juvenil.<\/p>\n<p>Durante la sesi\u00f3n realizaron recorrido sobre los ejes como modelos de comunicaci\u00f3n acordes con los principios y la misi\u00f3n de la Congregaci\u00f3n Salesiana, ayudar a desgranar en cada presencia salesiana las claves de identidad que justifican la comunicaci\u00f3n del modelo educativo y pastoral, dando respuesta a las demandas de la sociedad, desde herramientas de comunicaci\u00f3n, marketing, manejo de la imagen corporativa y gesti\u00f3n de crisis, o desarrollar un esquema conceptual de la presencia salesiana desde el punto de vista de la comunicaci\u00f3n sobre la planificaci\u00f3n y la gesti\u00f3n del plan local de comunicaci\u00f3n.<\/p>\n<p>Durante la segunda jornada de trabajo se cont\u00f3 con la participaci\u00f3n de Fernando Miranda, Vicario Inspectorial, que se hizo presente en el encuentro para compartir las opciones del Proyecto Org\u00e1nico Inspectorial, aprobado por el Consejo tras el trabajo realizado en M\u00e1laga el pasado mes de abril por el Cap\u00edtulo Inspectorial. Adem\u00e1s, esta cita permite avanzar en el plan de acompa\u00f1amiento propuesto, adem\u00e1s de compartir experiencias y crear sentido de pertenencia entre los participantes.<\/p>\n<\/div>\n<\/div>\n<div class=\"et_pb_button_module_wrapper et_pb_button_0_wrapper  et_pb_module \"><a class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\" href=\"https:\/\/drive.google.com\/drive\/u\/1\/folders\/1Un1Mu47Sf4rngO7JNj8-xNpfh4XCEFyp\" target=\"_blank\" rel=\"noopener\">Accede al documento para las obras gestionadas por seglares<\/a><\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante los d\u00edas 13 y 14 de octubre, en la casa salesiana de Sanl\u00facar la Mayor, se llev\u00f3 a cabo un nuevo encuentro de directores obras gestionadas por seglares de la Inspector\u00eda.<\/p>\n","protected":false},"author":2,"featured_media":14886,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12,23,13,17,14,15,18,16,1],"tags":[],"class_list":["post-14885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colegio","category-covid","category-fasa","category-infantil","category-pastoral","category-portada","category-primaria","category-secundaria","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encuentro de directores de Obras gestionadas por seglares - Colegio Salesiano Alcal\u00e1<\/title>\n<meta name=\"description\" content=\"Durante los d\u00edas 13 y 14 de octubre se llev\u00f3 a cabo un nuevo encuentro de directores obras gestionadas por seglares de la Inspector\u00eda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encuentro de directores de Obras gestionadas por seglares - Colegio Salesiano Alcal\u00e1\" \/>\n<meta property=\"og:description\" content=\"Durante los d\u00edas 13 y 14 de octubre se llev\u00f3 a cabo un nuevo encuentro de directores obras gestionadas por seglares de la Inspector\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Salesiano Alcal\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-14T08:06:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-27T07:47:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alcala.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/10\/5511a4f8-77e5-4d9f-a77e-f5ec617df8f6-e1665724868743-1536x737-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"737\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrador Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador Web\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2022\\\/10\\\/14\\\/directores-seglares-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2022\\\/10\\\/14\\\/directores-seglares-2\\\/\"},\"author\":{\"name\":\"Administrador Web\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/afcc24f776dc91fc2bf9afb0998fca77\"},\"headline\":\"Encuentro de directores de Obras gestionadas por seglares\",\"datePublished\":\"2022-10-14T08:06:37+00:00\",\"dateModified\":\"2025-08-27T07:47:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2022\\\/10\\\/14\\\/directores-seglares-2\\\/\"},\"wordCount\":445,\"image\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2022\\\/10\\\/14\\\/directores-seglares-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/10\\\/5511a4f8-77e5-4d9f-a77e-f5ec617df8f6-e1665724868743-1536x737-1.jpg\",\"articleSection\":[\"Colegio\",\"covid\",\"FASA\",\"Infantil\",\"Pastoral\",\"Portada\",\"Primaria\",\"Secundaria\",\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2022\\\/10\\\/14\\\/directores-seglares-2\\\/\",\"url\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2022\\\/10\\\/14\\\/directores-seglares-2\\\/\",\"name\":\"Encuentro de directores de Obras gestionadas por seglares - Colegio Salesiano Alcal\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2022\\\/10\\\/14\\\/directores-seglares-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2022\\\/10\\\/14\\\/directores-seglares-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/10\\\/5511a4f8-77e5-4d9f-a77e-f5ec617df8f6-e1665724868743-1536x737-1.jpg\",\"datePublished\":\"2022-10-14T08:06:37+00:00\",\"dateModified\":\"2025-08-27T07:47:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/afcc24f776dc91fc2bf9afb0998fca77\"},\"description\":\"Durante los d\u00edas 13 y 14 de octubre se llev\u00f3 a cabo un nuevo encuentro de directores obras gestionadas por seglares de la Inspector\u00eda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2022\\\/10\\\/14\\\/directores-seglares-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2022\\\/10\\\/14\\\/directores-seglares-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2022\\\/10\\\/14\\\/directores-seglares-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/10\\\/5511a4f8-77e5-4d9f-a77e-f5ec617df8f6-e1665724868743-1536x737-1.jpg\",\"contentUrl\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/10\\\/5511a4f8-77e5-4d9f-a77e-f5ec617df8f6-e1665724868743-1536x737-1.jpg\",\"width\":1536,\"height\":737},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2022\\\/10\\\/14\\\/directores-seglares-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encuentro de directores de Obras gestionadas por seglares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Salesiano Alcal\u00e1\",\"description\":\"P\u00e1gina oficial de Salesianos Alcal\u00e1 de Guadaira\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/afcc24f776dc91fc2bf9afb0998fca77\",\"name\":\"Administrador Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g\",\"caption\":\"Administrador Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encuentro de directores de Obras gestionadas por seglares - Colegio Salesiano Alcal\u00e1","description":"Durante los d\u00edas 13 y 14 de octubre se llev\u00f3 a cabo un nuevo encuentro de directores obras gestionadas por seglares de la Inspector\u00eda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/","og_locale":"es_ES","og_type":"article","og_title":"Encuentro de directores de Obras gestionadas por seglares - Colegio Salesiano Alcal\u00e1","og_description":"Durante los d\u00edas 13 y 14 de octubre se llev\u00f3 a cabo un nuevo encuentro de directores obras gestionadas por seglares de la Inspector\u00eda.","og_url":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/","og_site_name":"Colegio Salesiano Alcal\u00e1","article_published_time":"2022-10-14T08:06:37+00:00","article_modified_time":"2025-08-27T07:47:54+00:00","og_image":[{"width":1536,"height":737,"url":"https:\/\/alcala.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/10\/5511a4f8-77e5-4d9f-a77e-f5ec617df8f6-e1665724868743-1536x737-1.jpg","type":"image\/jpeg"}],"author":"Administrador Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Administrador Web"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/#article","isPartOf":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/"},"author":{"name":"Administrador Web","@id":"https:\/\/alcala.salesianos.edu\/colegio\/#\/schema\/person\/afcc24f776dc91fc2bf9afb0998fca77"},"headline":"Encuentro de directores de Obras gestionadas por seglares","datePublished":"2022-10-14T08:06:37+00:00","dateModified":"2025-08-27T07:47:54+00:00","mainEntityOfPage":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/"},"wordCount":445,"image":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/#primaryimage"},"thumbnailUrl":"https:\/\/alcala.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/10\/5511a4f8-77e5-4d9f-a77e-f5ec617df8f6-e1665724868743-1536x737-1.jpg","articleSection":["Colegio","covid","FASA","Infantil","Pastoral","Portada","Primaria","Secundaria","Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/","url":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/","name":"Encuentro de directores de Obras gestionadas por seglares - Colegio Salesiano Alcal\u00e1","isPartOf":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/#primaryimage"},"image":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/#primaryimage"},"thumbnailUrl":"https:\/\/alcala.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/10\/5511a4f8-77e5-4d9f-a77e-f5ec617df8f6-e1665724868743-1536x737-1.jpg","datePublished":"2022-10-14T08:06:37+00:00","dateModified":"2025-08-27T07:47:54+00:00","author":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/#\/schema\/person\/afcc24f776dc91fc2bf9afb0998fca77"},"description":"Durante los d\u00edas 13 y 14 de octubre se llev\u00f3 a cabo un nuevo encuentro de directores obras gestionadas por seglares de la Inspector\u00eda.","breadcrumb":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/#primaryimage","url":"https:\/\/alcala.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/10\/5511a4f8-77e5-4d9f-a77e-f5ec617df8f6-e1665724868743-1536x737-1.jpg","contentUrl":"https:\/\/alcala.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/10\/5511a4f8-77e5-4d9f-a77e-f5ec617df8f6-e1665724868743-1536x737-1.jpg","width":1536,"height":737},{"@type":"BreadcrumbList","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2022\/10\/14\/directores-seglares-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/alcala.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Encuentro de directores de Obras gestionadas por seglares"}]},{"@type":"WebSite","@id":"https:\/\/alcala.salesianos.edu\/colegio\/#website","url":"https:\/\/alcala.salesianos.edu\/colegio\/","name":"Colegio Salesiano Alcal\u00e1","description":"P\u00e1gina oficial de Salesianos Alcal\u00e1 de Guadaira","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alcala.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/alcala.salesianos.edu\/colegio\/#\/schema\/person\/afcc24f776dc91fc2bf9afb0998fca77","name":"Administrador Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g","caption":"Administrador Web"}}]}},"_links":{"self":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=14885"}],"version-history":[{"count":1,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14885\/revisions"}],"predecessor-version":[{"id":16637,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14885\/revisions\/16637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/14886"}],"wp:attachment":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=14885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=14885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=14885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}