{"id":14107,"date":"2021-06-18T08:46:22","date_gmt":"2021-06-18T07:46:22","guid":{"rendered":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/"},"modified":"2025-08-27T08:49:53","modified_gmt":"2025-08-27T07:49:53","slug":"examenes-de-certificacion-cambridge","status":"publish","type":"post","link":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/","title":{"rendered":"Ex\u00e1menes de certificaci\u00f3n Cambridge"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.5.8&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.5.8&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_column _builder_version=\u00bb4.5.8&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243;][et_pb_text _builder_version=\u00bb4.5.8&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243;]<\/p>\n<p>Durante el d\u00eda de ma\u00f1ana, <strong>s\u00e1bado 19 de junio,<\/strong> tendr\u00e1 lugar la convocatoria de los ex\u00e1menes de certificaci\u00f3n de Cambridge de los niveles A2, B1 y B2. La convocatoria para los ex\u00e1menes de Cambridge YLE, ser\u00e1 el pr\u00f3ximo <strong>jueves 24 de junio.<\/strong><\/p>\n<p>En estas pruebas, los alumnos ponen en pr\u00e1ctica las cuatro destrezas ling\u00fc\u00edsticas<em>:<\/em>\u00a0comprensi\u00f3n lectora\u00a0<em>(Reading)<\/em>, expresi\u00f3n escrita (<em>Writing<\/em>), compresi\u00f3n auditiva (<em>Listening<\/em>) y expresi\u00f3n oral (<em>Speaking<\/em>) a trav\u00e9s de distintos ejercicios para los cuales se preparan durante el curso.<\/p>\n<p>Gracias a la labor que realiza a diario el equipo docente al promover el uso de la lengua extranjera como segundo idioma, nuestro alumnado, tiene adquirido un buen dominio de las competencias ling\u00fc\u00edsticas esenciales para poder desenvolverse en el mundo globalizado en el que vivimos.<\/p>\n<p>Nos sentimos muy orgullosos de su esfuerzo y evoluci\u00f3n y les deseamos mucho \u00e9xito en sus resultados.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante el d\u00eda de ma\u00f1ana, s\u00e1bado 19 de junio, tendr\u00e1 lugar la convocatoria de los ex\u00e1menes de certificaci\u00f3n de Cambridge de los niveles A2, B1 y B2. <\/p>\n","protected":false},"author":2,"featured_media":12878,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12,23,19,13,17,14,15,18,16,1],"tags":[],"class_list":["post-14107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colegio","category-covid","category-escuela-abierta","category-fasa","category-infantil","category-pastoral","category-portada","category-primaria","category-secundaria","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ex\u00e1menes de certificaci\u00f3n Cambridge - Colegio Salesiano Alcal\u00e1<\/title>\n<meta name=\"description\" content=\"Durante el d\u00eda de ma\u00f1ana, s\u00e1bado 19 de junio, tendr\u00e1 lugar la convocatoria de los ex\u00e1menes de certificaci\u00f3n de Cambridge de los niveles A2, B1 y B2.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ex\u00e1menes de certificaci\u00f3n Cambridge - Colegio Salesiano Alcal\u00e1\" \/>\n<meta property=\"og:description\" content=\"Durante el d\u00eda de ma\u00f1ana, s\u00e1bado 19 de junio, tendr\u00e1 lugar la convocatoria de los ex\u00e1menes de certificaci\u00f3n de Cambridge de los niveles A2, B1 y B2.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Salesiano Alcal\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-18T07:46:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-27T07:49:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alcala.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/SalesianosAlcala.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrador Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/06\\\/18\\\/examenes-de-certificacion-cambridge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/06\\\/18\\\/examenes-de-certificacion-cambridge\\\/\"},\"author\":{\"name\":\"Administrador Web\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/afcc24f776dc91fc2bf9afb0998fca77\"},\"headline\":\"Ex\u00e1menes de certificaci\u00f3n Cambridge\",\"datePublished\":\"2021-06-18T07:46:22+00:00\",\"dateModified\":\"2025-08-27T07:49:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/06\\\/18\\\/examenes-de-certificacion-cambridge\\\/\"},\"wordCount\":211,\"image\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/06\\\/18\\\/examenes-de-certificacion-cambridge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/SalesianosAlcala.jpg\",\"articleSection\":[\"Colegio\",\"covid\",\"Escuela abierta\",\"FASA\",\"Infantil\",\"Pastoral\",\"Portada\",\"Primaria\",\"Secundaria\",\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/06\\\/18\\\/examenes-de-certificacion-cambridge\\\/\",\"url\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/06\\\/18\\\/examenes-de-certificacion-cambridge\\\/\",\"name\":\"Ex\u00e1menes de certificaci\u00f3n Cambridge - Colegio Salesiano Alcal\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/06\\\/18\\\/examenes-de-certificacion-cambridge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/06\\\/18\\\/examenes-de-certificacion-cambridge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/SalesianosAlcala.jpg\",\"datePublished\":\"2021-06-18T07:46:22+00:00\",\"dateModified\":\"2025-08-27T07:49:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/afcc24f776dc91fc2bf9afb0998fca77\"},\"description\":\"Durante el d\u00eda de ma\u00f1ana, s\u00e1bado 19 de junio, tendr\u00e1 lugar la convocatoria de los ex\u00e1menes de certificaci\u00f3n de Cambridge de los niveles A2, B1 y B2.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/06\\\/18\\\/examenes-de-certificacion-cambridge\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/06\\\/18\\\/examenes-de-certificacion-cambridge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/06\\\/18\\\/examenes-de-certificacion-cambridge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/SalesianosAlcala.jpg\",\"contentUrl\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/SalesianosAlcala.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2021\\\/06\\\/18\\\/examenes-de-certificacion-cambridge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ex\u00e1menes de certificaci\u00f3n Cambridge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Salesiano Alcal\u00e1\",\"description\":\"P\u00e1gina oficial de Salesianos Alcal\u00e1 de Guadaira\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/afcc24f776dc91fc2bf9afb0998fca77\",\"name\":\"Administrador Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g\",\"caption\":\"Administrador Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ex\u00e1menes de certificaci\u00f3n Cambridge - Colegio Salesiano Alcal\u00e1","description":"Durante el d\u00eda de ma\u00f1ana, s\u00e1bado 19 de junio, tendr\u00e1 lugar la convocatoria de los ex\u00e1menes de certificaci\u00f3n de Cambridge de los niveles A2, B1 y B2.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/","og_locale":"es_ES","og_type":"article","og_title":"Ex\u00e1menes de certificaci\u00f3n Cambridge - Colegio Salesiano Alcal\u00e1","og_description":"Durante el d\u00eda de ma\u00f1ana, s\u00e1bado 19 de junio, tendr\u00e1 lugar la convocatoria de los ex\u00e1menes de certificaci\u00f3n de Cambridge de los niveles A2, B1 y B2.","og_url":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/","og_site_name":"Colegio Salesiano Alcal\u00e1","article_published_time":"2021-06-18T07:46:22+00:00","article_modified_time":"2025-08-27T07:49:53+00:00","og_image":[{"url":"https:\/\/alcala.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/SalesianosAlcala.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"Administrador Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Administrador Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/#article","isPartOf":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/"},"author":{"name":"Administrador Web","@id":"https:\/\/alcala.salesianos.edu\/colegio\/#\/schema\/person\/afcc24f776dc91fc2bf9afb0998fca77"},"headline":"Ex\u00e1menes de certificaci\u00f3n Cambridge","datePublished":"2021-06-18T07:46:22+00:00","dateModified":"2025-08-27T07:49:53+00:00","mainEntityOfPage":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/"},"wordCount":211,"image":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/#primaryimage"},"thumbnailUrl":"https:\/\/alcala.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/SalesianosAlcala.jpg","articleSection":["Colegio","covid","Escuela abierta","FASA","Infantil","Pastoral","Portada","Primaria","Secundaria","Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/","url":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/","name":"Ex\u00e1menes de certificaci\u00f3n Cambridge - Colegio Salesiano Alcal\u00e1","isPartOf":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/#primaryimage"},"image":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/#primaryimage"},"thumbnailUrl":"https:\/\/alcala.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/SalesianosAlcala.jpg","datePublished":"2021-06-18T07:46:22+00:00","dateModified":"2025-08-27T07:49:53+00:00","author":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/#\/schema\/person\/afcc24f776dc91fc2bf9afb0998fca77"},"description":"Durante el d\u00eda de ma\u00f1ana, s\u00e1bado 19 de junio, tendr\u00e1 lugar la convocatoria de los ex\u00e1menes de certificaci\u00f3n de Cambridge de los niveles A2, B1 y B2.","breadcrumb":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/#primaryimage","url":"https:\/\/alcala.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/SalesianosAlcala.jpg","contentUrl":"https:\/\/alcala.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2020\/10\/SalesianosAlcala.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2021\/06\/18\/examenes-de-certificacion-cambridge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/alcala.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Ex\u00e1menes de certificaci\u00f3n Cambridge"}]},{"@type":"WebSite","@id":"https:\/\/alcala.salesianos.edu\/colegio\/#website","url":"https:\/\/alcala.salesianos.edu\/colegio\/","name":"Colegio Salesiano Alcal\u00e1","description":"P\u00e1gina oficial de Salesianos Alcal\u00e1 de Guadaira","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alcala.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/alcala.salesianos.edu\/colegio\/#\/schema\/person\/afcc24f776dc91fc2bf9afb0998fca77","name":"Administrador Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g","caption":"Administrador Web"}}]}},"_links":{"self":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=14107"}],"version-history":[{"count":1,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14107\/revisions"}],"predecessor-version":[{"id":16693,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/14107\/revisions\/16693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/12878"}],"wp:attachment":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=14107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=14107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=14107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}