{"id":13099,"date":"2020-10-27T09:04:51","date_gmt":"2020-10-27T08:04:51","guid":{"rendered":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/"},"modified":"2025-08-27T08:51:03","modified_gmt":"2025-08-27T07:51:03","slug":"carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2","status":"publish","type":"post","link":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/","title":{"rendered":"Carlo Acutis y Domingo Savio: la santidad juvenil no pasa de moda"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.5.8&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.5.8&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.5.8&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_text _builder_version=\u00bb4.5.8&#8243; _module_preset=\u00bbdefault\u00bb]<\/p>\n<p><strong>Vida de piedad precoz<\/strong><br \/>Pese a que la fe no se viv\u00eda con intensidad en su familia, Carlo demostr\u00f3 pronto su gusto por rezar en las iglesias. Su madre tuvo que apuntarse a clases de teolog\u00eda para poder contestar a las cuestiones que planteaba el ni\u00f1o. Tambi\u00e9n Domingo Savio ten\u00eda una inquietud espiritual desde peque\u00f1o, cuando ayudaba en misa como monaguillo.<\/p>\n<p><strong>Vivencia eucar\u00edstica<\/strong><br \/>Ambos muchachos recibieron la primera comuni\u00f3n cuando ten\u00edan 7 a\u00f1os. Desde entonces, tuvieron una profunda vivencia eucar\u00edstica. \u201cEstar siempre unido a Jes\u00fas, ese es mi proyecto de vida\u201d, afirmaba Carlo. El joven acud\u00eda diariamente a misa y encontraba en la Eucarist\u00eda una \u201cautopista hacia el Cielo\u201d. Domingo Savio tambi\u00e9n sigui\u00f3 este camino desde la primera vez que recibi\u00f3 a Jes\u00fas Sacramentado: \u201cMe confesar\u00e9 a menudo, y comulgar\u00e9 tan frecuentemente como mi confesor lo permita. Mis amigos ser\u00e1n Jes\u00fas y Mar\u00eda\u201d, expres\u00f3 entre los deseos tras su primera comuni\u00f3n.<\/p>\n<p><strong>Devoci\u00f3n mariana<\/strong><br \/>Carlo rezaba diariamente el rosario. Ten\u00eda devoci\u00f3n por la Virgen Mar\u00eda, especialmente en sus advocaciones de Lourdes y F\u00e1tima. Domingo, por su parte, fue promotor de la devoci\u00f3n a la Inmaculada Concepci\u00f3n hasta el punto de fundar la Compa\u00f1\u00eda de la Inmaculada dos a\u00f1os despu\u00e9s de la declaraci\u00f3n de este dogma mariano por parte del Papa P\u00edo IX.<\/p>\n<p><strong>Imitaci\u00f3n de los santos<\/strong><br \/>De Carlo se dice que mostraba inter\u00e9s por la vida de santos como Francisco de As\u00eds, Antonio de Padua, los tres pastores de la Virgen de F\u00e1tima y el propio Domingo Savio. De los referentes para el joven piamont\u00e9s se sabe poco, pero lo cierto es que tuvo como maestro a un santo en vida: Don Bosco.<\/p>\n<p><strong>Caridad y buen hacer en lo peque\u00f1o<\/strong><br \/>La expresi\u00f3n del amor de Dios era habitual en las vidas de Carlo y Domingo. El primero pasaba tiempo con ancianos, enfermos y, sobre todo, personas sin hogar. Muchas de ellas se hicieron presentes en su funeral. Adem\u00e1s, era catequista. Domingo tambi\u00e9n instru\u00eda en la fe a otros muchachos del oratorio e, incluso, a los adultos. Estaba atento a las necesidades de sus compa\u00f1eros marginados por otros y a aquellos que enfermaban. Ambos eran conscientes de que sus deseos de santidad pasaban por los peque\u00f1os detalles, por lo cotidiano. De ambos se dice que eran buenos estudiantes, bondadosos y amables. Adem\u00e1s, ten\u00edan aficiones propias de su edad.<\/p>\n<p><strong>Alegr\u00eda cristiana<\/strong><br \/>Dice el Papa Francisco que \u201cel cristiano es un hombre o una mujer alegre\u201d. Carlo y Domingo acogieron la exhortaci\u00f3n paulina de la alegr\u00eda en toda circunstancia. Pero, \u00bfde d\u00f3nde nace esa alegr\u00eda? \u201cLa tristeza es dirigir la mirada hacia uno mismo, la felicidad es dirigir la mirada hacia Dios. La conversi\u00f3n no es otra cosa que desviar la mirada desde abajo hacia lo alto. Basta un simple movimiento de ojo\u201d, manifestaba Carlo. No en vano, Domingo afirmaba que \u201cla santidad consiste en estar siempre alegres\u201d.<\/p>\n<p><strong>Inspiraci\u00f3n para los dem\u00e1s<\/strong><br \/>La forma de vivir la fe de ambos j\u00f3venes era contagiosa. Raejsh, un hombre hind\u00fa que limpiaba en la casa de Carlo, se convirti\u00f3 gracias a su ejemplo de sencillez: \u201cMe contagi\u00f3 y cautiv\u00f3 con su profunda fe, caridad y pureza\u201d. Domingo, por su parte, dej\u00f3 una huella profunda en el alma del mismo Don Bosco: \u201cPuedo decir que en todo este tiempo no tuve en mi escuela un muchacho parecido a Domingo en la amistad con el Se\u00f1or. Era joven de edad, pero sensato como un adulto. Su dedicaci\u00f3n constante al estudio y su cumplida bondad atra\u00edan el afecto del maestro y lo hac\u00edan amigo de todos\u201d, afirmaba el santo sacerdote.<\/p>\n<p><strong>Emprendedores de la fe<\/strong><br \/>Ambos j\u00f3venes emprendieron diferentes empresas para dar gloria a Dios. Carlo abri\u00f3 con la ayuda de sus padres una web sobre los milagros eucar\u00edsticos en todo el mundo, una de las razones por las que es conocido como el \u2018ciberap\u00f3stol\u2019 de la Eucarist\u00eda. Para promover el apostolado entre sus propios compa\u00f1eros, Domingo fund\u00f3 la Compa\u00f1\u00eda de la Inmaculada, con reglamento que fue aprobado por Don Bosco. Es el testimonio de su profunda espiritualidad.<\/p>\n<p><strong>Sentido del sufrimiento<\/strong><br \/>Cuando Carlo ingres\u00f3 en el hospital por la leucemia que padec\u00eda, consciente de que su muerte estaba cerca, expres\u00f3: \u201cOfrezco al Se\u00f1or los sufrimientos que tendr\u00e9 que padecer por el Papa y por la Iglesia cat\u00f3lica, para no tener que estar en el Purgatorio y poder ir directo al Cielo\u201d. Era el culmen de una lucha espiritual desarrollada durante su breve vida: \u201cDe qu\u00e9 sirve ganar 1000 batallas si no puedes vencer tus propias pasiones\u201d, sol\u00eda decir. Tambi\u00e9n Domingo se forj\u00f3 en actitudes extraordinarias, a trav\u00e9s de sacrificios como comer la mitad de su raci\u00f3n, dormir menos o dedicar m\u00e1s tiempo a rezar.<\/p>\n<p><strong>La muerte como pasarela para la Vida<\/strong><br \/>Para Carlo y Domingo, lo m\u00e1s importante era vivir en amistad permanente con Dios. \u201cEstoy contento de morir porque he vivido mi vida sin malgastar ni un solo minuto de ella en cosas que no le gustan a Dios\u201d, afirm\u00f3 Carlo. Es el desarrollo de una de las frases m\u00e1s celebres de Domingo Savio: \u201cAntes morir que pecar\u201d. Las \u00faltimas palabras del joven oratoriano, seg\u00fan Don Bosco, fueron: \u201c\u00a1Qu\u00e9 maravilla estoy viendo!\u201d. Ambos pasaron a la Vida en torno a los 15 a\u00f1os.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ejemplo de santidad del Siglo XXI, Carlos Acutis fue beatificado el pasado 10 de octubre en As\u00eds.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12,13,17,14,15,18,16,1],"tags":[],"class_list":["post-13099","post","type-post","status-publish","format-standard","hentry","category-colegio","category-fasa","category-infantil","category-pastoral","category-portada","category-primaria","category-secundaria","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carlo Acutis y Domingo Savio: la santidad juvenil no pasa de moda - Colegio Salesiano Alcal\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carlo Acutis y Domingo Savio: la santidad juvenil no pasa de moda - Colegio Salesiano Alcal\u00e1\" \/>\n<meta property=\"og:description\" content=\"Ejemplo de santidad del Siglo XXI, Carlos Acutis fue beatificado el pasado 10 de octubre en As\u00eds.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Salesiano Alcal\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-27T08:04:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-27T07:51:03+00:00\" \/>\n<meta name=\"author\" content=\"Administrador Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/27\\\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/27\\\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\\\/\"},\"author\":{\"name\":\"Administrador Web\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/afcc24f776dc91fc2bf9afb0998fca77\"},\"headline\":\"Carlo Acutis y Domingo Savio: la santidad juvenil no pasa de moda\",\"datePublished\":\"2020-10-27T08:04:51+00:00\",\"dateModified\":\"2025-08-27T07:51:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/27\\\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\\\/\"},\"wordCount\":996,\"articleSection\":[\"Colegio\",\"FASA\",\"Infantil\",\"Pastoral\",\"Portada\",\"Primaria\",\"Secundaria\",\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/27\\\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\\\/\",\"url\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/27\\\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\\\/\",\"name\":\"Carlo Acutis y Domingo Savio: la santidad juvenil no pasa de moda - Colegio Salesiano Alcal\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#website\"},\"datePublished\":\"2020-10-27T08:04:51+00:00\",\"dateModified\":\"2025-08-27T07:51:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/afcc24f776dc91fc2bf9afb0998fca77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/27\\\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/27\\\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/27\\\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carlo Acutis y Domingo Savio: la santidad juvenil no pasa de moda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Salesiano Alcal\u00e1\",\"description\":\"P\u00e1gina oficial de Salesianos Alcal\u00e1 de Guadaira\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/afcc24f776dc91fc2bf9afb0998fca77\",\"name\":\"Administrador Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g\",\"caption\":\"Administrador Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carlo Acutis y Domingo Savio: la santidad juvenil no pasa de moda - Colegio Salesiano Alcal\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/","og_locale":"es_ES","og_type":"article","og_title":"Carlo Acutis y Domingo Savio: la santidad juvenil no pasa de moda - Colegio Salesiano Alcal\u00e1","og_description":"Ejemplo de santidad del Siglo XXI, Carlos Acutis fue beatificado el pasado 10 de octubre en As\u00eds.","og_url":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/","og_site_name":"Colegio Salesiano Alcal\u00e1","article_published_time":"2020-10-27T08:04:51+00:00","article_modified_time":"2025-08-27T07:51:03+00:00","author":"Administrador Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Administrador Web","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/#article","isPartOf":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/"},"author":{"name":"Administrador Web","@id":"https:\/\/alcala.salesianos.edu\/colegio\/#\/schema\/person\/afcc24f776dc91fc2bf9afb0998fca77"},"headline":"Carlo Acutis y Domingo Savio: la santidad juvenil no pasa de moda","datePublished":"2020-10-27T08:04:51+00:00","dateModified":"2025-08-27T07:51:03+00:00","mainEntityOfPage":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/"},"wordCount":996,"articleSection":["Colegio","FASA","Infantil","Pastoral","Portada","Primaria","Secundaria","Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/","url":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/","name":"Carlo Acutis y Domingo Savio: la santidad juvenil no pasa de moda - Colegio Salesiano Alcal\u00e1","isPartOf":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/#website"},"datePublished":"2020-10-27T08:04:51+00:00","dateModified":"2025-08-27T07:51:03+00:00","author":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/#\/schema\/person\/afcc24f776dc91fc2bf9afb0998fca77"},"breadcrumb":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/27\/carlo-acutis-y-domingo-savio-la-santidad-juvenil-no-pasa-de-moda-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/alcala.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Carlo Acutis y Domingo Savio: la santidad juvenil no pasa de moda"}]},{"@type":"WebSite","@id":"https:\/\/alcala.salesianos.edu\/colegio\/#website","url":"https:\/\/alcala.salesianos.edu\/colegio\/","name":"Colegio Salesiano Alcal\u00e1","description":"P\u00e1gina oficial de Salesianos Alcal\u00e1 de Guadaira","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alcala.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/alcala.salesianos.edu\/colegio\/#\/schema\/person\/afcc24f776dc91fc2bf9afb0998fca77","name":"Administrador Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g","caption":"Administrador Web"}}]}},"_links":{"self":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/13099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=13099"}],"version-history":[{"count":1,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/13099\/revisions"}],"predecessor-version":[{"id":16722,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/13099\/revisions\/16722"}],"wp:attachment":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=13099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=13099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=13099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}