{"id":13003,"date":"2020-10-21T14:16:26","date_gmt":"2020-10-21T13:16:26","guid":{"rendered":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/"},"modified":"2025-08-27T08:51:07","modified_gmt":"2025-08-27T07:51:07","slug":"beneficios-y-salud-nutricional-en-nuestro-comedor-escolar","status":"publish","type":"post","link":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/","title":{"rendered":"Beneficios y salud nutricional en nuestro comedor escolar"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.5.8&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.5.8&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.5.8&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_text _builder_version=\u00bb4.5.8&#8243; _module_preset=\u00bbdefault\u00bb]<\/p>\n<p>Nuestro comedor escolar se reinventa ante las dificultades derivadas de la crisis sanitaria. Con esto, a\u00f1ade exigentes medidas de seguridad, ordenaci\u00f3n y regulaci\u00f3n del aforo para que la atenci\u00f3n del alumnado no se vea mermada.<\/p>\n<p>El comedor escolar es un lugar seguro en el que se prioriza la salud nutricional de los m\u00e1s peque\u00f1os de nuestro centro. Cada mes en la web de nuestro centro est\u00e1 disponible el men\u00fa diario. Este men\u00fa cuanta con\u00a0 proyecto de alimentaci\u00f3n saludable, equilibrada y segura.<\/p>\n<p><em><a href=\"https:\/\/www.serunion-educa.com\/quienes-somos\/\">Serunion<\/a><span>\u00a0<\/span>es la empresa que nos da el servicio de nuestro comedor escolar. Aconsejamos que visiten su<span>\u00a0<\/span><a href=\"https:\/\/www.comollevarunavidasaludable.es\/\">blog<\/a><span>\u00a0<\/span>educativo en el que nos recomiendan c\u00f3mo llevar una vida saludable.<\/em><\/p>\n<p><em>En dicho<span>\u00a0<\/span><a href=\"https:\/\/www.comollevarunavidasaludable.es\/\">blog<\/a><span>\u00a0<\/span>incorporan informaciones de vuestro inter\u00e9s en relaci\u00f3n con el comedor, pero tambi\u00e9n de aspectos generales como consejos de salud, actividades para hacer en familia o recetas para hacer en casa, entre otros.<\/em><\/p>\n<p>Por \u00faltimo, recordamos que nuestro comedor a\u00f1ade como novedad al centro, desde el curso 2019\/20 la cocina de todos sus alimentos in situ.\u00a0<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Importancia de nuestro servicio de comedor en el que seguimos con un proyecto de alimentaci\u00f3n saludable, equilibrada y segura.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12,23,19,13,17,15,18,16,1],"tags":[],"class_list":["post-13003","post","type-post","status-publish","format-standard","hentry","category-colegio","category-covid","category-escuela-abierta","category-fasa","category-infantil","category-portada","category-primaria","category-secundaria","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beneficios y salud nutricional en nuestro comedor escolar - Colegio Salesiano Alcal\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beneficios y salud nutricional en nuestro comedor escolar - Colegio Salesiano Alcal\u00e1\" \/>\n<meta property=\"og:description\" content=\"Importancia de nuestro servicio de comedor en el que seguimos con un proyecto de alimentaci\u00f3n saludable, equilibrada y segura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Salesiano Alcal\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-21T13:16:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-27T07:51:07+00:00\" \/>\n<meta name=\"author\" content=\"Administrador Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/21\\\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/21\\\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\\\/\"},\"author\":{\"name\":\"Administrador Web\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/afcc24f776dc91fc2bf9afb0998fca77\"},\"headline\":\"Beneficios y salud nutricional en nuestro comedor escolar\",\"datePublished\":\"2020-10-21T13:16:26+00:00\",\"dateModified\":\"2025-08-27T07:51:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/21\\\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\\\/\"},\"wordCount\":234,\"articleSection\":[\"Colegio\",\"covid\",\"Escuela abierta\",\"FASA\",\"Infantil\",\"Portada\",\"Primaria\",\"Secundaria\",\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/21\\\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\\\/\",\"url\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/21\\\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\\\/\",\"name\":\"Beneficios y salud nutricional en nuestro comedor escolar - Colegio Salesiano Alcal\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#website\"},\"datePublished\":\"2020-10-21T13:16:26+00:00\",\"dateModified\":\"2025-08-27T07:51:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/afcc24f776dc91fc2bf9afb0998fca77\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/21\\\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/21\\\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/blog\\\/2020\\\/10\\\/21\\\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beneficios y salud nutricional en nuestro comedor escolar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Salesiano Alcal\u00e1\",\"description\":\"P\u00e1gina oficial de Salesianos Alcal\u00e1 de Guadaira\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/afcc24f776dc91fc2bf9afb0998fca77\",\"name\":\"Administrador Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g\",\"caption\":\"Administrador Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beneficios y salud nutricional en nuestro comedor escolar - Colegio Salesiano Alcal\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/","og_locale":"es_ES","og_type":"article","og_title":"Beneficios y salud nutricional en nuestro comedor escolar - Colegio Salesiano Alcal\u00e1","og_description":"Importancia de nuestro servicio de comedor en el que seguimos con un proyecto de alimentaci\u00f3n saludable, equilibrada y segura.","og_url":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/","og_site_name":"Colegio Salesiano Alcal\u00e1","article_published_time":"2020-10-21T13:16:26+00:00","article_modified_time":"2025-08-27T07:51:07+00:00","author":"Administrador Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Administrador Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/#article","isPartOf":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/"},"author":{"name":"Administrador Web","@id":"https:\/\/alcala.salesianos.edu\/colegio\/#\/schema\/person\/afcc24f776dc91fc2bf9afb0998fca77"},"headline":"Beneficios y salud nutricional en nuestro comedor escolar","datePublished":"2020-10-21T13:16:26+00:00","dateModified":"2025-08-27T07:51:07+00:00","mainEntityOfPage":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/"},"wordCount":234,"articleSection":["Colegio","covid","Escuela abierta","FASA","Infantil","Portada","Primaria","Secundaria","Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/","url":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/","name":"Beneficios y salud nutricional en nuestro comedor escolar - Colegio Salesiano Alcal\u00e1","isPartOf":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/#website"},"datePublished":"2020-10-21T13:16:26+00:00","dateModified":"2025-08-27T07:51:07+00:00","author":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/#\/schema\/person\/afcc24f776dc91fc2bf9afb0998fca77"},"breadcrumb":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alcala.salesianos.edu\/colegio\/blog\/2020\/10\/21\/beneficios-y-salud-nutricional-en-nuestro-comedor-escolar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/alcala.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Beneficios y salud nutricional en nuestro comedor escolar"}]},{"@type":"WebSite","@id":"https:\/\/alcala.salesianos.edu\/colegio\/#website","url":"https:\/\/alcala.salesianos.edu\/colegio\/","name":"Colegio Salesiano Alcal\u00e1","description":"P\u00e1gina oficial de Salesianos Alcal\u00e1 de Guadaira","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alcala.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/alcala.salesianos.edu\/colegio\/#\/schema\/person\/afcc24f776dc91fc2bf9afb0998fca77","name":"Administrador Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc157e994689bd6da9645c00aa3bc4d55b727915b6652642660db0aef086585f?s=96&d=mm&r=g","caption":"Administrador Web"}}]}},"_links":{"self":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/13003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=13003"}],"version-history":[{"count":2,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/13003\/revisions"}],"predecessor-version":[{"id":13007,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/13003\/revisions\/13007"}],"wp:attachment":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=13003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=13003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=13003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}