{"id":5315,"date":"2018-01-21T18:02:44","date_gmt":"2018-01-21T17:02:44","guid":{"rendered":"https:\/\/alcala.salesianos.edu\/colegio\/?page_id=5315"},"modified":"2025-10-29T12:53:39","modified_gmt":"2025-10-29T11:53:39","slug":"programaciones-de-2o-ep","status":"publish","type":"page","link":"https:\/\/alcala.salesianos.edu\/colegio\/programaciones-de-2o-ep\/","title":{"rendered":"Programaciones de 2\u00ba ep"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.19.5&#8243; background_color=\u00bb#dc001b\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header title=\u00bbProgramaciones de 2\u00ba E.P.\u00bb text_orientation=\u00bbcenter\u00bb module_class=\u00bbpagina-imagen-cabecera\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bbrgba(255, 255, 255, 0)\u00bb background_image=\u00bbhttps:\/\/inspectoria.salesianos.edu\/wp-content\/uploads\/2017\/09\/ImagenPAGINA.jpg\u00bb background_layout=\u00bblight\u00bb max_width_tablet=\u00bb50px\u00bb global_colors_info=\u00bb{}\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]<br \/>\n[\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb25px|||\u00bb custom_padding=\u00bb25px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbDescargar programaci\u00f3n de lengua\u00bb url=\u00bbhttps:\/\/alcala.salesianos.edu\/wp-content\/uploads\/2025\/10\/Lengua_Castellana_y_Literatura-2o_de_Educ._Prima.pdf\u00bb url_new_window=\u00bbon\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x69;||divi||400&#8243; admin_label=\u00bbLengua\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bbLato||||\u00bb header_font_size=\u00bb20px\u00bb body_font=\u00bbLato Light||||\u00bb body_font_size=\u00bb13px\u00bb text_orientation=\u00bbcenter\u00bb max_width_tablet=\u00bb50px\u00bb hover_enabled=\u00bb0&#8243; z_index_tablet=\u00bb500&#8243; header_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_link_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_link_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_link_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_ul_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_ul_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_ul_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_ol_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_ol_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_ol_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_quote_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_quote_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_quote_text_shadow_blur_strength_tablet=\u00bb1px\u00bb box_shadow_horizontal_tablet=\u00bb0px\u00bb box_shadow_vertical_tablet=\u00bb0px\u00bb box_shadow_blur_tablet=\u00bb40px\u00bb box_shadow_spread_tablet=\u00bb0px\u00bb box_shadow_horizontal_image_tablet=\u00bb0px\u00bb box_shadow_vertical_image_tablet=\u00bb0px\u00bb box_shadow_blur_image_tablet=\u00bb40px\u00bb box_shadow_spread_image_tablet=\u00bb0px\u00bb text_shadow_horizontal_length_tablet=\u00bb0px\u00bb text_shadow_vertical_length_tablet=\u00bb0px\u00bb text_shadow_blur_strength_tablet=\u00bb1px\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][et_pb_blurb title=\u00bbDescargar programaci\u00f3n de Religi\u00f3n\u00bb url=\u00bbhttps:\/\/alcala.salesianos.edu\/wp-content\/uploads\/2025\/10\/Religion-2o_de_Educ._Prima.pdf\u00bb url_new_window=\u00bbon\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x69;||divi||400&#8243; admin_label=\u00bbNatural\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bbLato||||\u00bb header_font_size=\u00bb20px\u00bb body_font=\u00bbLato Light||||\u00bb body_font_size=\u00bb13px\u00bb text_orientation=\u00bbcenter\u00bb max_width_tablet=\u00bb50px\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbDescargar programaci\u00f3n de matem\u00e1ticas\u00bb url=\u00bbhttps:\/\/alcala.salesianos.edu\/wp-content\/uploads\/2025\/10\/Matematicas-2o_de_Educ._Prima.pdf\u00bb url_new_window=\u00bbon\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x69;||divi||400&#8243; admin_label=\u00bbMatem\u00e1ticas\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bbLato||||\u00bb header_font_size=\u00bb20px\u00bb body_font=\u00bbLato Light||||\u00bb body_font_size=\u00bb13px\u00bb text_orientation=\u00bbcenter\u00bb max_width_tablet=\u00bb50px\u00bb hover_enabled=\u00bb0&#8243; z_index_tablet=\u00bb500&#8243; header_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_link_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_link_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_link_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_ul_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_ul_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_ul_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_ol_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_ol_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_ol_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_quote_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_quote_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_quote_text_shadow_blur_strength_tablet=\u00bb1px\u00bb box_shadow_horizontal_tablet=\u00bb0px\u00bb box_shadow_vertical_tablet=\u00bb0px\u00bb box_shadow_blur_tablet=\u00bb40px\u00bb box_shadow_spread_tablet=\u00bb0px\u00bb box_shadow_horizontal_image_tablet=\u00bb0px\u00bb box_shadow_vertical_image_tablet=\u00bb0px\u00bb box_shadow_blur_image_tablet=\u00bb40px\u00bb box_shadow_spread_image_tablet=\u00bb0px\u00bb text_shadow_horizontal_length_tablet=\u00bb0px\u00bb text_shadow_vertical_length_tablet=\u00bb0px\u00bb text_shadow_blur_strength_tablet=\u00bb1px\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][et_pb_blurb title=\u00bbDescargar programaci\u00f3n de Conocimiento del Medio\u00bb url_new_window=\u00bbon\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x69;||divi||400&#8243; admin_label=\u00bbSocial\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bbLato||||\u00bb header_font_size=\u00bb20px\u00bb body_font=\u00bbLato Light||||\u00bb body_font_size=\u00bb13px\u00bb text_orientation=\u00bbcenter\u00bb max_width_tablet=\u00bb50px\u00bb hover_enabled=\u00bb0&#8243; z_index_tablet=\u00bb500&#8243; header_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_link_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_link_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_link_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_ul_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_ul_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_ul_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_ol_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_ol_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_ol_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_quote_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_quote_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_quote_text_shadow_blur_strength_tablet=\u00bb1px\u00bb box_shadow_horizontal_tablet=\u00bb0px\u00bb box_shadow_vertical_tablet=\u00bb0px\u00bb box_shadow_blur_tablet=\u00bb40px\u00bb box_shadow_spread_tablet=\u00bb0px\u00bb box_shadow_horizontal_image_tablet=\u00bb0px\u00bb box_shadow_vertical_image_tablet=\u00bb0px\u00bb box_shadow_blur_image_tablet=\u00bb40px\u00bb box_shadow_spread_image_tablet=\u00bb0px\u00bb text_shadow_horizontal_length_tablet=\u00bb0px\u00bb text_shadow_vertical_length_tablet=\u00bb0px\u00bb text_shadow_blur_strength_tablet=\u00bb1px\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbDescargar programaci\u00f3n de ingl\u00e9s\u00bb url_new_window=\u00bbon\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x69;||divi||400&#8243; admin_label=\u00bbIngl\u00e9s\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bbLato||||\u00bb header_font_size=\u00bb20px\u00bb body_font=\u00bbLato Light||||\u00bb body_font_size=\u00bb13px\u00bb text_orientation=\u00bbcenter\u00bb max_width_tablet=\u00bb50px\u00bb hover_enabled=\u00bb0&#8243; z_index_tablet=\u00bb500&#8243; header_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb header_text_shadow_vertical_length_tablet=\u00bb0px\u00bb header_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_link_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_link_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_link_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_ul_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_ul_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_ul_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_ol_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_ol_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_ol_text_shadow_blur_strength_tablet=\u00bb1px\u00bb body_quote_text_shadow_horizontal_length_tablet=\u00bb0px\u00bb body_quote_text_shadow_vertical_length_tablet=\u00bb0px\u00bb body_quote_text_shadow_blur_strength_tablet=\u00bb1px\u00bb box_shadow_horizontal_tablet=\u00bb0px\u00bb box_shadow_vertical_tablet=\u00bb0px\u00bb box_shadow_blur_tablet=\u00bb40px\u00bb box_shadow_spread_tablet=\u00bb0px\u00bb box_shadow_horizontal_image_tablet=\u00bb0px\u00bb box_shadow_vertical_image_tablet=\u00bb0px\u00bb box_shadow_blur_image_tablet=\u00bb40px\u00bb box_shadow_spread_image_tablet=\u00bb0px\u00bb text_shadow_horizontal_length_tablet=\u00bb0px\u00bb text_shadow_vertical_length_tablet=\u00bb0px\u00bb text_shadow_blur_strength_tablet=\u00bb1px\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][et_pb_blurb title=\u00bbDescargar programaci\u00f3n de pl\u00e1stica\u00bb url=\u00bbhttps:\/\/alcala.salesianos.edu\/wp-content\/uploads\/2025\/10\/Plastica-2o_de_Educ._Prima.-1.pdf\u00bb url_new_window=\u00bbon\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x69;||divi||400&#8243; admin_label=\u00bbArts\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bbLato||||\u00bb header_font_size=\u00bb20px\u00bb body_font=\u00bbLato Light||||\u00bb body_font_size=\u00bb13px\u00bb text_orientation=\u00bbcenter\u00bb max_width_tablet=\u00bb50px\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbDescargar programaci\u00f3n de m\u00fasica\u00bb url_new_window=\u00bbon\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x69;||divi||400&#8243; admin_label=\u00bbM\u00fasica\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bbLato||||\u00bb header_font_size=\u00bb20px\u00bb body_font=\u00bbLato Light||||\u00bb body_font_size=\u00bb13px\u00bb text_orientation=\u00bbcenter\u00bb max_width_tablet=\u00bb50px\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][et_pb_blurb title=\u00bbDescargar programaci\u00f3n de E.F.\u00bb url=\u00bbhttps:\/\/alcala.salesianos.edu\/wp-content\/uploads\/2025\/10\/Educacion_Fisica-2o_de_Educ._Prima.pdf\u00bb url_new_window=\u00bbon\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x69;||divi||400&#8243; admin_label=\u00bbE.F.\u00bb _builder_version=\u00bb4.27.4&#8243; header_font=\u00bbLato||||\u00bb header_font_size=\u00bb20px\u00bb body_font=\u00bbLato Light||||\u00bb body_font_size=\u00bb13px\u00bb text_orientation=\u00bbcenter\u00bb max_width_tablet=\u00bb50px\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-5315","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Programaciones de 2\u00ba ep - Colegio Salesiano Alcal\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alcala.salesianos.edu\/colegio\/programaciones-de-2o-ep\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programaciones de 2\u00ba ep - Colegio Salesiano Alcal\u00e1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alcala.salesianos.edu\/colegio\/programaciones-de-2o-ep\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Salesiano Alcal\u00e1\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T11:53:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/programaciones-de-2o-ep\\\/\",\"url\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/programaciones-de-2o-ep\\\/\",\"name\":\"Programaciones de 2\u00ba ep - Colegio Salesiano Alcal\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#website\"},\"datePublished\":\"2018-01-21T17:02:44+00:00\",\"dateModified\":\"2025-10-29T11:53:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/programaciones-de-2o-ep\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/programaciones-de-2o-ep\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/programaciones-de-2o-ep\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programaciones de 2\u00ba ep\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Salesiano Alcal\u00e1\",\"description\":\"P\u00e1gina oficial de Salesianos Alcal\u00e1 de Guadaira\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alcala.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programaciones de 2\u00ba ep - Colegio Salesiano Alcal\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alcala.salesianos.edu\/colegio\/programaciones-de-2o-ep\/","og_locale":"es_ES","og_type":"article","og_title":"Programaciones de 2\u00ba ep - Colegio Salesiano Alcal\u00e1","og_url":"https:\/\/alcala.salesianos.edu\/colegio\/programaciones-de-2o-ep\/","og_site_name":"Colegio Salesiano Alcal\u00e1","article_modified_time":"2025-10-29T11:53:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alcala.salesianos.edu\/colegio\/programaciones-de-2o-ep\/","url":"https:\/\/alcala.salesianos.edu\/colegio\/programaciones-de-2o-ep\/","name":"Programaciones de 2\u00ba ep - Colegio Salesiano Alcal\u00e1","isPartOf":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/#website"},"datePublished":"2018-01-21T17:02:44+00:00","dateModified":"2025-10-29T11:53:39+00:00","breadcrumb":{"@id":"https:\/\/alcala.salesianos.edu\/colegio\/programaciones-de-2o-ep\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alcala.salesianos.edu\/colegio\/programaciones-de-2o-ep\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/alcala.salesianos.edu\/colegio\/programaciones-de-2o-ep\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/alcala.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Programaciones de 2\u00ba ep"}]},{"@type":"WebSite","@id":"https:\/\/alcala.salesianos.edu\/colegio\/#website","url":"https:\/\/alcala.salesianos.edu\/colegio\/","name":"Colegio Salesiano Alcal\u00e1","description":"P\u00e1gina oficial de Salesianos Alcal\u00e1 de Guadaira","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alcala.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/5315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=5315"}],"version-history":[{"count":21,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/5315\/revisions"}],"predecessor-version":[{"id":16791,"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/5315\/revisions\/16791"}],"wp:attachment":[{"href":"https:\/\/alcala.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=5315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}